{"id":25,"date":"2005-04-16T00:39:52","date_gmt":"2005-04-15T22:39:52","guid":{"rendered":"http:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/?page_id=25"},"modified":"2017-11-01T16:38:25","modified_gmt":"2017-11-01T14:38:25","slug":"halle","status":"publish","type":"page","link":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/halle\/","title":{"rendered":"Die Halle"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"_links":{"self":[{"href":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-json\/wp\/v2\/pages\/25"}],"collection":[{"href":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":4,"href":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":3705,"href":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-json\/wp\/v2\/pages\/25\/revisions\/3705"}],"wp:attachment":[{"href":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}