{"id":2917,"date":"2016-06-22T21:53:06","date_gmt":"2016-06-22T19:53:06","guid":{"rendered":"http:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-content\/uploads\/P1480857.jpg"},"modified":"2016-06-22T21:53:06","modified_gmt":"2016-06-22T19:53:06","slug":"p1480857","status":"inherit","type":"attachment","link":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/bilder-schuetzenfest-2016\/p1480857\/","title":{"rendered":"P1480857"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"description":{"rendered":"<p class=\"attachment\"><a class=\"grouped_elements\" rel=\"tc-fancybox-group\" href=\"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-content\/uploads\/P1480857.jpg\" title=\"P1480857\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-content\/uploads\/P1480857-225x300.jpg\" class=\"attachment-medium size-medium no-lazy\" alt=\"\" srcset=\"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-content\/uploads\/P1480857-225x300.jpg 225w, https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-content\/uploads\/P1480857-768x1024.jpg 768w, https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-content\/uploads\/P1480857-619x826.jpg 619w, https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-content\/uploads\/P1480857.jpg 800w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":1067,"file":"P1480857.jpg","sizes":{"thumbnail":{"file":"P1480857-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-content\/uploads\/P1480857-150x150.jpg"},"medium":{"file":"P1480857-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-content\/uploads\/P1480857-225x300.jpg"},"medium_large":{"file":"P1480857-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-content\/uploads\/P1480857-768x1024.jpg"},"large":{"file":"P1480857-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-content\/uploads\/P1480857-768x1024.jpg"},"mistylake-thumbnail":{"file":"P1480857-619x826.jpg","width":619,"height":826,"mime_type":"image\/jpeg","source_url":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-content\/uploads\/P1480857-619x826.jpg"},"full":{"file":"P1480857.jpg","width":800,"height":1067,"mime_type":"image\/jpeg","source_url":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-content\/uploads\/P1480857.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2661,"source_url":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-content\/uploads\/P1480857.jpg","_links":{"self":[{"href":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-json\/wp\/v2\/media\/2917"}],"collection":[{"href":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schuetzengesellschaft-lichtringhausen.de\/html\/wp-json\/wp\/v2\/comments?post=2917"}]}}